{"id":13649,"date":"2020-12-01T11:43:33","date_gmt":"2020-12-01T10:43:33","guid":{"rendered":"https:\/\/blog.esmadrid.com\/blog\/es\/?p=13649"},"modified":"2020-12-01T20:10:35","modified_gmt":"2020-12-01T19:10:35","slug":"adornos-navidad-artesanos","status":"publish","type":"post","link":"https:\/\/blog.esmadrid.com\/blog\/es\/2020\/12\/01\/adornos-navidad-artesanos\/","title":{"rendered":"Adornos navide\u00f1os y madrile\u00f1os"},"content":{"rendered":"<div id=\"attachment_13673\" style=\"width: 633px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-13673\" loading=\"lazy\" class=\"size-full wp-image-13673\" title=\"Estos arboles de colores son velas de la centenaria Cerer\u00eda Ortega.\" src=\"https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/00a0288.jpg\" alt=\"Estos arboles de colores son velas de la centenaria Cerer\u00eda Ortega.\" width=\"623\" height=\"356\" srcset=\"https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/00a0288.jpg 623w, https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/00a0288-300x171.jpg 300w\" sizes=\"(max-width: 623px) 100vw, 623px\" \/><p id=\"caption-attachment-13673\" class=\"wp-caption-text\">Estos arboles de colores son velas de la centenaria Cerer\u00eda Ortega (\u00a9 \u00c1lvaro L\u00f3pez del Cerro)..<\/p><\/div>\n<p>Queda muy poco tiempo para que llegue la Navidad pero quiz\u00e1s ya sea hora sacar el \u00e1rbol del desv\u00e1n,<strong> adornar la casa<\/strong> y pensar en c\u00f3mo y con qu\u00e9 vamos a preparar la mesa en Nochebuena aunque nos juntemos pocos. Nuestra ciudad est\u00e1 repleta de <strong>tiendas y talleres artesanos<\/strong> en los que podr\u00e9is encontrar detalles muy especiales,<strong> hechos aqu\u00ed, en Madrid.<\/strong> Aqu\u00ed van unas cuantas ideas.<!--more--><\/p>\n<div id=\"attachment_13672\" style=\"width: 633px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-13672\" loading=\"lazy\" class=\"size-full wp-image-13672\" title=\"Una bola de cer\u00e1mica de D\u00e9borah Abizand para celebrar la Navidad.\" src=\"https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/bola-2020-topos.jpg\" alt=\"Una bola de cer\u00e1mica de D\u00e9borah Abizand para celebrar la Navidad.\" width=\"623\" height=\"356\" srcset=\"https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/bola-2020-topos.jpg 623w, https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/bola-2020-topos-300x171.jpg 300w\" sizes=\"(max-width: 623px) 100vw, 623px\" \/><p id=\"caption-attachment-13672\" class=\"wp-caption-text\">Una bola de cer\u00e1mica de D\u00e9borah Abizand para celebrar la Navidad.<\/p><\/div>\n<p>\u201cCon la cer\u00e1mica puedo crear obras tangibles, un contrapunto al mundo tecnol\u00f3gico que nos rodea, algo que me produce gran satisfacci\u00f3n\u201d. As\u00ed habla\u00a0<strong>D\u00e9borah Abizanda<\/strong>, que desde\u00a0<a href=\"https:\/\/deborah-abizanda.es\/bio\/\" target=\"_blank\"><strong>D\u2019A Ceramics<\/strong><\/a>, su tienda-estudio ubicada en la calle Doctor Fourquet 11, prepara unas preciosas <strong>bolas de cer\u00e1mica<\/strong>\u00a0para alegrar el \u00e1rbol de Navidad. Hasta ahora ten\u00eda cuatro modelos, <strong>decoradas a mano<\/strong>, con dibujos de cuernos de reno, puntitos de colores, rombos y estrellas doradas.<\/p>\n<div id=\"attachment_13671\" style=\"width: 633px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-13671\" loading=\"lazy\" class=\"size-full wp-image-13671\" title=\"Estas son las bolas navide\u00f1as de la nueva colecci\u00f3n de D\u00e9borah Abizanda.\" src=\"https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/bola-nuevos-modelos2020.jpg\" alt=\"Estas son las bolas navide\u00f1as de la nueva colecci\u00f3n de D\u00e9borah Abizanda.\" width=\"623\" height=\"356\" srcset=\"https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/bola-nuevos-modelos2020.jpg 623w, https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/bola-nuevos-modelos2020-300x171.jpg 300w\" sizes=\"(max-width: 623px) 100vw, 623px\" \/><p id=\"caption-attachment-13671\" class=\"wp-caption-text\">Estas son las bolas navide\u00f1as de la nueva colecci\u00f3n de D\u00e9borah Abizanda.<\/p><\/div>\n<p>Este a\u00f1o ha ampliado su particular colecci\u00f3n con bolas de cer\u00e1mica con <strong>efecto marmolado<\/strong>, inspiradas en las aguadas de color que crea la t\u00e9cnica japonesa sobre el papel, llamada\u00a0<em>suminagashi<\/em>.\u00a0\u00a1Puedes escoger! Porque las tiene en distintos colores: rosa, rojo, azul, gris y verde, todas ellas con<strong> detalles dorados.<\/strong><\/p>\n<div id=\"attachment_13670\" style=\"width: 633px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-13670\" loading=\"lazy\" class=\"size-full wp-image-13670\" title=\"Estos adornos de loza son de Vajillas de Ultramar.\" src=\"https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/set-figuritas-vdv-1.jpg\" alt=\"Estos adornos de loza son de Vajillas de Ultramar.\" width=\"623\" height=\"356\" srcset=\"https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/set-figuritas-vdv-1.jpg 623w, https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/set-figuritas-vdv-1-300x171.jpg 300w\" sizes=\"(max-width: 623px) 100vw, 623px\" \/><p id=\"caption-attachment-13670\" class=\"wp-caption-text\">Estos adornos de loza son de Vajillas de Ultramar.<\/p><\/div>\n<p><strong>De loza blanca hechas a mano,<\/strong> muy ligeras, ideales para colgar en el \u00e1rbol o, simplemente, colocar sobre la mesa, son las <strong>figuritas<\/strong> <strong>en<\/strong> <strong>forma de coraz\u00f3n, abetos, p\u00e1jaros y estrellas<\/strong> que puedes adquirir en\u00a0<a href=\"https:\/\/www.vajillasdeultramar.com\" target=\"_blank\"><strong>Vajillas de Ultramar<\/strong><\/a>, la firma creada por Natalia L\u00f3pez y Mar\u00eda Jos\u00e9 D\u00edez que une<strong> dise\u00f1o, modernidad y tradici\u00f3n<\/strong> a trav\u00e9s de piezas hechas a mano, como \u00e9stas, con un \u201cacabado deliberadamente imperfecto\u201d.<\/p>\n<div id=\"attachment_13669\" style=\"width: 633px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-13669\" loading=\"lazy\" class=\"size-full wp-image-13669\" title=\"En los talleres que organiza Amasarte te ense\u00f1an a hacer tus propios adornos.\" src=\"https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/dsc0575.jpg\" alt=\"En los talleres que organiza Amasarte te ense\u00f1an a hacer tus propios adornos.\" width=\"623\" height=\"356\" srcset=\"https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/dsc0575.jpg 623w, https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/dsc0575-300x171.jpg 300w\" sizes=\"(max-width: 623px) 100vw, 623px\" \/><p id=\"caption-attachment-13669\" class=\"wp-caption-text\">En los talleres que organiza Amasarte te ense\u00f1an a hacer tus propios adornos.<\/p><\/div>\n<p>Si eres de los que prefiere hacer t\u00fa mismo tus propias bolas o figuras no puedes dejar de pasarte por\u00a0<strong><a href=\"Amasarte\" target=\"_blank\">Amasarte<\/a>\u00a0<\/strong>(Minas, 6), un<strong> taller escuela del barrio de Malasa\u00f1a<\/strong> dedicado a la cer\u00e1mica art\u00edstica abierto de par en para a todos aquellos que comienzan a descubrir o quieren potenciar sus habilidades. <strong>El d\u00eda 5, de 11 a 13h, organizan un taller de creaci\u00f3n de adornos<\/strong> <strong>navide\u00f1os<\/strong>. \u00a1Ap\u00fantate! No hay l\u00edmites creativos, m\u00e1s que los que pone el material, en este caso el <strong>barro<\/strong>. Aqu\u00ed te ense\u00f1ar\u00e1n diferentes t\u00e9cnicas de construcci\u00f3n y decoraci\u00f3n. Y lo mejor: al cabo de una semana podr\u00e1s recoger tu obra una vez haya pasado por el horno.<\/p>\n<div id=\"attachment_13662\" style=\"width: 633px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-13662\" loading=\"lazy\" class=\"size-full wp-image-13662\" title=\"Estas talegas para casta\u00f1as de Eutorel tienen sabor rural.\" src=\"https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/eturel-talega-navidad_0002_capa-2.jpg\" alt=\"Estas talegas para casta\u00f1as de Eutorel tienen sabor rural.\" width=\"623\" height=\"356\" srcset=\"https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/eturel-talega-navidad_0002_capa-2.jpg 623w, https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/eturel-talega-navidad_0002_capa-2-300x171.jpg 300w\" sizes=\"(max-width: 623px) 100vw, 623px\" \/><p id=\"caption-attachment-13662\" class=\"wp-caption-text\">Estas talegas para casta\u00f1as de Eturel tienen sabor rural.<\/p><\/div>\n<p><strong>Arpillera, alpujarra y loneta\u00a0<\/strong>son la materia prima con la que trabaja Eduardo para dar vida, desde\u00a0<a href=\"Eturel\" target=\"_blank\"><strong>Eturel<\/strong><\/a>\u00a0(Ruda, 8) a un sinf\u00edn de piezas, cada cual m\u00e1s original, inspiradas en el mundo rural. Para Navidad ha preparado una colecci\u00f3n basada en los recuerdos familiares, con su puntito de nostalgia. Sus <strong>bolas para el \u00e1rbol<\/strong>, confeccionadas a mano, son diferentes a todas las que hayas podido ver.<\/p>\n<div id=\"attachment_13663\" style=\"width: 633px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-13663\" loading=\"lazy\" class=\"size-full wp-image-13663\" title=\"\u00a1Qu\u00e9 bonitos son los manteles de Eturel! La Oficial (laoficialceramica.com).\" src=\"https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/eturel-mantel-individual-navidad_0001s_0005_capa-17.jpg\" alt=\"\u00a1Qu\u00e9 bonitos son los manteles de Eturel! La Oficial (laoficialceramica.com).\" width=\"623\" height=\"356\" srcset=\"https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/eturel-mantel-individual-navidad_0001s_0005_capa-17.jpg 623w, https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/eturel-mantel-individual-navidad_0001s_0005_capa-17-300x171.jpg 300w\" sizes=\"(max-width: 623px) 100vw, 623px\" \/><p id=\"caption-attachment-13663\" class=\"wp-caption-text\">\u00a1Qu\u00e9 bonitos son los manteles de Eturel! <a href=\"http:\/\/laoficialceramica.com\" target=\"_blank\">La Oficial<\/a>.<\/p><\/div>\n<p>Con sus caracter\u00edsticas<strong> rayas y en tonos crudos, rojos y verdes<\/strong> Eduardo tambi\u00e9n ha dise\u00f1ado para estas fiestas unos <strong>sacos y talegas<\/strong>, perfectos para colocar los frutos secos, las peladillas, los polvorones y el turr\u00f3n. Aunque tambi\u00e9n puedes dejarlos vac\u00edos y esperar a que los llenen de regalos los Reyes Magos\u2026<\/p>\n<div id=\"attachment_13668\" style=\"width: 633px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/blog.esmadrid.com\/blog\/es\/2020\/12\/01\/adornos-navidad-artesanos\/sallyhambleton_phornellabinni_-2\/\" rel=\"attachment wp-att-13668\"><img aria-describedby=\"caption-attachment-13668\" loading=\"lazy\" class=\"size-full wp-image-13668\" title=\"En Sally Hambleton preparan unas preciosas coronas de flores como \u00e9s (Foto: OrnellaBinni).\" src=\"https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/sallyhambleton_phornellabinni_-2.jpg\" alt=\"En Sally Hambleton preparan unas preciosas coronas de flores como \u00e9s (Foto: OrnellaBinni).\" width=\"623\" height=\"356\" srcset=\"https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/sallyhambleton_phornellabinni_-2.jpg 623w, https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/sallyhambleton_phornellabinni_-2-300x171.jpg 300w\" sizes=\"(max-width: 623px) 100vw, 623px\" \/><\/a><p id=\"caption-attachment-13668\" class=\"wp-caption-text\">En Sally Hambleton preparan unas preciosas coronas de flores como \u00e9s (Foto: OrnellaBinni).<\/p><\/div>\n<p>Tanto si esperas a los Reyes como a Pap\u00e1 Noel tendr\u00e1s que recibirlos bien. Y para eso nada mejor que colocar en tu puerta una <strong>corona de flores<\/strong>. Espectaculares son las que vende<a href=\"https:\/\/sallyhambleton.com\" target=\"_blank\">\u00a0<strong>Sally Hambleton<\/strong><\/a>\u00a0(Gabriel Lobo, 10). Esta que ves en la foto est\u00e1 realizada con <strong>hortensias, escaramujo, verdes navide\u00f1os, adornos y un gran lazo de seda.<\/strong> Pero tambi\u00e9n tienen corazones de boj artificial pintados de purpurina color champagne, estrellas plateadas de minicascabeles y much\u00edsimas ideas para tener la casa perfecta en estas fechas.<\/p>\n<div id=\"attachment_13657\" style=\"width: 633px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-13657\" loading=\"lazy\" class=\"size-full wp-image-13657\" title=\"\u00a1La Navidad est\u00e1 en la mesa! Y esta es la propuesta de L'Alacena.\" src=\"https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/lalacena_navidad_bajoplato_02.jpg\" alt=\"\u00a1La Navidad est\u00e1 en la mesa! Y esta es la propuesta de L'Alacena.\" width=\"623\" height=\"356\" srcset=\"https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/lalacena_navidad_bajoplato_02.jpg 623w, https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/lalacena_navidad_bajoplato_02-300x171.jpg 300w\" sizes=\"(max-width: 623px) 100vw, 623px\" \/><p id=\"caption-attachment-13657\" class=\"wp-caption-text\">\u00a1La Navidad est\u00e1 en la mesa! Y esta es la propuesta de L&#8217;Alacena.<\/p><\/div>\n<p>Para la hora de la comida o la cena te van a encantar los<strong> tapetes y bajoplatos<\/strong> de<a href=\"https:\/\/lalacena.es\" target=\"_blank\">\u00a0<strong>L\u2019Alacena<\/strong><\/a>\u00a0hechos con <strong>arpillera estampada<\/strong>. Atenci\u00f3n al proceso de realizaci\u00f3n. Antes de estampar cada arpillera, deshilachan los laterales para darle un efecto m\u00e1s r\u00fastico. Y despu\u00e9s aplican una especie de pegamento que fija los hilos para evitar que se deshilache por completo.<\/p>\n<div id=\"attachment_13658\" style=\"width: 633px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-13658\" loading=\"lazy\" class=\"size-full wp-image-13658\" title=\"Los tapetes y bajoplatos de L'Alacena son verdes, azules... \u00a1y tienen estrellas!\" src=\"https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/lalacena_navidad_tapeteverde_04.jpg\" alt=\"Los tapetes y bajoplatos de L'Alacena son verdes, azules... \u00a1y tienen estrellas!\" width=\"623\" height=\"356\" srcset=\"https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/lalacena_navidad_tapeteverde_04.jpg 623w, https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/lalacena_navidad_tapeteverde_04-300x171.jpg 300w\" sizes=\"(max-width: 623px) 100vw, 623px\" \/><p id=\"caption-attachment-13658\" class=\"wp-caption-text\">Los tapetes y bajoplatos de L&#8217;Alacena son verdes, azules&#8230; \u00a1y tienen estrellas!<\/p><\/div>\n<p>Para la decoraci\u00f3n utilizan la t\u00e9cnica del\u00a0<em>stencil<\/em>. Bocetan a mano el dise\u00f1o, lo pasan a formato digital y lo imprimen en 3D con hilo de un pol\u00edmero de ma\u00edz. El resultado es una plantilla muy finita, con una apariencia similar al pl\u00e1stico, a la que luego dan peque\u00f1os golpecitos con <strong>esponja y pintura<\/strong>. Toda una obra de arte.<\/p>\n<div id=\"attachment_13659\" style=\"width: 633px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-13659\" loading=\"lazy\" class=\"size-full wp-image-13659\" title=\"Con las vajillas de Eva's Sand es muy f\u00e1cil triunfar.\" src=\"https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/servicio-boda-rusti.jpg\" alt=\"Con las vajillas de Eva's Sand es muy f\u00e1cil triunfar.\" width=\"623\" height=\"356\" srcset=\"https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/servicio-boda-rusti.jpg 623w, https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/servicio-boda-rusti-300x171.jpg 300w\" sizes=\"(max-width: 623px) 100vw, 623px\" \/><p id=\"caption-attachment-13659\" class=\"wp-caption-text\">Con las vajillas de Eva&#8217;s Sand es muy f\u00e1cil triunfar.<\/p><\/div>\n<p>Obra de arte son tambi\u00e9n las <strong>vajillas<\/strong> de\u00a0<a href=\"Eva\u2019s Sand\" target=\"_blank\"><strong>Eva\u2019s Sand<\/strong><\/a>, una enamorada de la cer\u00e1mica desde que, de ni\u00f1a, visitaba tiendas de menaje con su abuela. <strong>El barro, la porcelana y los esmaltes<\/strong> forman ahora parte de su universo\u00a0<em>slow<\/em>, \u201clleno de sensaciones, satisfacci\u00f3n y libertad\u201d. Adem\u00e1s de preciosos <strong>platos<\/strong> este a\u00f1o tambi\u00e9n ha incorporado a su cat\u00e1logo unas <strong>velas<\/strong> perfectas para iluminar estas fiestas.<\/p>\n<div id=\"attachment_13655\" style=\"width: 633px\" class=\"wp-caption alignnone\"><img aria-describedby=\"caption-attachment-13655\" loading=\"lazy\" class=\"size-full wp-image-13655\" title=\"Velas con forma de abetos para la mesa navide\u00f1a de Cerer\u00eda Ortega (\u00a9 \u00c1lvaro L\u00f3pez del Cerro).\" src=\"https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/00a0206.jpg\" alt=\"Velas con forma de abetos para la mesa navide\u00f1a de Cerer\u00eda Ortega (\u00a9 \u00c1lvaro L\u00f3pez del Cerro).\" width=\"623\" height=\"356\" srcset=\"https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/00a0206.jpg 623w, https:\/\/blog.esmadrid.com\/blog\/es\/wp-content\/uploads\/2020\/11\/00a0206-300x171.jpg 300w\" sizes=\"(max-width: 623px) 100vw, 623px\" \/><p id=\"caption-attachment-13655\" class=\"wp-caption-text\">Velas con forma de abetos para la mesa navide\u00f1a de Cerer\u00eda Ortega (\u00a9 \u00c1lvaro L\u00f3pez del Cerro).<\/p><\/div>\n<p>\u00bfHemos dicho velas? Entonces llega el momento de pasarnos por la\u00a0<a href=\"https:\/\/www.cereriaortega.es\" target=\"_blank\"><strong>Cerer\u00eda Ortega<\/strong>\u00a0<\/a>(Toledo, 43), fundada all\u00e1 por el a\u00f1o 1893. Un <strong>comercio centenario<\/strong>, junto a la iglesia de san Isidro, que ha sabido mantener, durante cuatro generaciones ya, <strong>un oficio con siglos de tradici\u00f3n<\/strong>. En Navidad tienen muchos modelos para elegir. Escoge una, enciende la llama <strong>\u00a1y disfruta de estas fiestas!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Queda muy poco tiempo para que llegue la Navidad pero quiz\u00e1s ya sea hora sacar el \u00e1rbol del desv\u00e1n, adornar la casa y pensar en c\u00f3mo y con qu\u00e9 vamos a preparar la mesa en Nochebuena aunque nos juntemos pocos. Nuestra ciudad est\u00e1 repleta de tiendas y talleres artesanos en los que podr\u00e9is encontrar detalles [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":13677,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[587,948,551],"_links":{"self":[{"href":"https:\/\/blog.esmadrid.com\/blog\/es\/wp-json\/wp\/v2\/posts\/13649"}],"collection":[{"href":"https:\/\/blog.esmadrid.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.esmadrid.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.esmadrid.com\/blog\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.esmadrid.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=13649"}],"version-history":[{"count":26,"href":"https:\/\/blog.esmadrid.com\/blog\/es\/wp-json\/wp\/v2\/posts\/13649\/revisions"}],"predecessor-version":[{"id":13689,"href":"https:\/\/blog.esmadrid.com\/blog\/es\/wp-json\/wp\/v2\/posts\/13649\/revisions\/13689"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.esmadrid.com\/blog\/es\/wp-json\/wp\/v2\/media\/13677"}],"wp:attachment":[{"href":"https:\/\/blog.esmadrid.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=13649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.esmadrid.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=13649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.esmadrid.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=13649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}